{"id":16315,"date":"2021-07-13T10:38:02","date_gmt":"2021-07-13T08:38:02","guid":{"rendered":"https:\/\/www.linkfacts.link\/cartes-conceptuelles\/"},"modified":"2022-02-03T16:31:39","modified_gmt":"2022-02-03T14:31:39","slug":"cartes-conceptuelles","status":"publish","type":"page","link":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/","title":{"rendered":"Cartes conceptuelles"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"16315\" class=\"elementor elementor-16315 elementor-14737\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-66ee6b0d elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"66ee6b0d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-347905\" data-id=\"347905\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7940559c landing-hero elementor-widget elementor-widget-saasland_hero\" data-id=\"7940559c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"saasland_hero.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"agency_banner_area\">\r\n    <img decoding=\"async\" class=\"banner_shap\" src=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png\" alt=\"Outil gratuit de cartes conceptuelles en ligne\">\r\n    <div class=\"container custom_container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-lg-5 d-flex align-items-center\">\r\n                <div class=\"agency_content\">\r\n                                            <h1 class=\"typewrite_title f_700 t_color3 mb_40 wow fadeInLeft\" data-wow-delay=\"0.3s\">Outil gratuit de cartes conceptuelles en ligne<\/h1>\r\n                                                                <p class=\"f_300 l_height28 wow fadeInLeft\" data-wow-delay=\"0.4s\">\r\n                            Visualisez et clarifiez des concepts simples ou complexes avec LinkFacts.\u202fReliez des documents, des ic\u00f4nes, des notes ou des formes pour visualiser les liens entre les id\u00e9es et les sujets dans votre carte conceptuelle.<br \/>\r\n<ul class=\"fa-ul\"><br \/>\r\n  <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span> Visualisez vos informations <\/li><br \/>\r\n  <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Partagez, commentez, \u00e9valuez<\/li><br \/>\r\n  <li><span class=\"fa-li\"><i class=\"fas fa-check-circle\"><\/i><\/span>Joignez des sources et des documents <\/li><br \/>\r\n<\/ul>                        <\/p>\r\n                                    <div class=\"action_btn d-flex align-items-center mt_60\">\r\n                    <a href='https:\/\/one.linkfacts.link\/user\/signUp' data-wow-delay='0.5s'class='btn_hover agency_banner_btn wow fadeInLeft elementor-repeater-item-b7782f6'> Commencer gratuitement <\/a><a href='https:\/\/www.trustpilot.com\/review\/linkfacts.link' data-wow-delay='0.7s'class='agency_banner_btn_two wow fadeInLeft elementor-repeater-item-34e2f08'> <img decoding=\"async\" src=\"\/wp-content\/uploads\/2021\/08\/Reviews-black-v3.png\"> <\/a>                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n        <div class=\"col-lg-7 text-right\">\r\n            <img fetchpriority=\"high\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/Concept-2.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/Concept-2.png 900w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/Concept-2-300x225.png 300w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/Concept-2-768x576.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/>        <\/div>\r\n    <\/div>\r\n    <div class=\"partner_logo\">\r\n            <\/div>\r\n<\/section>\r\n\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5b86160f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5b86160f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-66656ff3\" data-id=\"66656ff3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-41ff9bd features-block elementor-widget elementor-widget-saasland_main_features\" data-id=\"41ff9bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"saasland_main_features.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <section class=\"prototype_service_area_three\">\r\n                <div class=\"container\">\r\n                    <div class=\"prototype_service_info\">\r\n                        <div class=\"symbols-pulse active\">\r\n                            <div class=\"pulse-1\"><\/div>\r\n                            <div class=\"pulse-2\"><\/div>\r\n                            <div class=\"pulse-3\"><\/div>\r\n                            <div class=\"pulse-4\"><\/div>\r\n                            <div class=\"pulse-x\"><\/div>\r\n                        <\/div>\r\n\r\n                                                    <h2 class=\"f_size_30 f_600 t_color3 l_height45 text-center mb_90 wow fadeInUp\" data-wow-delay=\"0.3s\">\r\n                                Des fonctionnalit\u00e9s d\u00e9di\u00e9es \u00e0 la cr\u00e9ation de cartes conceptuelles                            <\/h2>\r\n                        \r\n                        <div class=\"row p_service_info\">\r\n                                                                <div class=\"col-lg-4 col-sm-6\">\r\n                                        <div class=\"p_service_item pr_70 wow fadeInLeft\" data-wow-delay=\"0.2s\">\r\n                                            <div class=\"icon icon_one elementor-repeater-item-3fd8846\">\r\n                                                                                                    <i class=\"fas fa-layer-group\"><\/i>\r\n                                                                                                <\/div>\r\n                                            <h3 class=\"f_600 f_p t_color3\">\r\n                                                Visualisation flexible des n\u0153uds et des connexions                                            <\/h3>\r\n                                                                                            <p class=\"f_300\"> Utilisez des ic\u00f4nes, des formes, des textes et vos propres images pour faire passer votre message. <\/p>\r\n                                                                                    <\/div>\r\n                                    <\/div>\r\n                                                                        <div class=\"col-lg-4 col-sm-6\">\r\n                                        <div class=\"p_service_item pr_70 wow fadeInLeft\" data-wow-delay=\"0.4s\">\r\n                                            <div class=\"icon icon_one elementor-repeater-item-a6f7106\">\r\n                                                                                                    <i class=\"far fa-copy\"><\/i>\r\n                                                                                                <\/div>\r\n                                            <h3 class=\"f_600 f_p t_color3\">\r\n                                                Glissez-d\u00e9posez des documents et des sites web                                            <\/h3>\r\n                                                                                            <p class=\"f_300\"> Ajoutez des notes, des liens vers des sites Web externes, des images, des vid\u00e9os et des fichiers entiers \u00e0 vos cartes mentales. <\/p>\r\n                                                                                    <\/div>\r\n                                    <\/div>\r\n                                                                        <div class=\"col-lg-4 col-sm-6\">\r\n                                        <div class=\"p_service_item pr_70 wow fadeInLeft\" data-wow-delay=\"0.6s\">\r\n                                            <div class=\"icon icon_one elementor-repeater-item-17aa872\">\r\n                                                                                                    <i class=\"fas fa-th\"><\/i>\r\n                                                                                                <\/div>\r\n                                            <h3 class=\"f_600 f_p t_color3\">\r\n                                                Mod\u00e8les de graphes pr\u00e9-con\u00e7us                                            <\/h3>\r\n                                                                                            <p class=\"f_300\"> LinkFacts est \u00e9quip\u00e9 d'une galerie enti\u00e8re de mod\u00e8les con\u00e7us pour vous. <\/p>\r\n                                                                                    <\/div>\r\n                                    <\/div>\r\n                                                                        <div class=\"col-lg-4 col-sm-6\">\r\n                                        <div class=\"p_service_item pr_70 wow fadeInLeft\" data-wow-delay=\"0.8s\">\r\n                                            <div class=\"icon icon_one elementor-repeater-item-c5950fb\">\r\n                                                                                                    <i class=\"far fa-eye\"><\/i>\r\n                                                                                                <\/div>\r\n                                            <h3 class=\"f_600 f_p t_color3\">\r\n                                                Des types de vue pour offrir des perspectives diff\u00e9rentes au public                                            <\/h3>\r\n                                                                                            <p class=\"f_300\"> Cr\u00e9ez plusieurs vues et structurez votre contenu \u00e0 l'aide de d\u00e9pendances graphes, de layers et de filtres.  <\/p>\r\n                                                                                    <\/div>\r\n                                    <\/div>\r\n                                                                        <div class=\"col-lg-4 col-sm-6\">\r\n                                        <div class=\"p_service_item pr_70 wow fadeInLeft\" data-wow-delay=\"1s\">\r\n                                            <div class=\"icon icon_one elementor-repeater-item-aa0b2ff\">\r\n                                                                                                    <i class=\"fas fa-user-friends\"><\/i>\r\n                                                                                                <\/div>\r\n                                            <h3 class=\"f_600 f_p t_color3\">\r\n                                                Collaboration en \u00e9quipe et interaction avec les utilisateurs                                            <\/h3>\r\n                                                                                            <p class=\"f_300\"> Partagez des graphes et invitez vos coll\u00e8gues \u00e0 donner leur avis et \u00e0 contribuer \u00e0 votre processus de planification. <\/p>\r\n                                                                                    <\/div>\r\n                                    <\/div>\r\n                                                                        <div class=\"col-lg-4 col-sm-6\">\r\n                                        <div class=\"p_service_item pr_70 wow fadeInLeft\" data-wow-delay=\"1.2s\">\r\n                                            <div class=\"icon icon_one elementor-repeater-item-75d1c70\">\r\n                                                                                                    <i class=\"far fa-arrow-alt-circle-down\"><\/i>\r\n                                                                                                <\/div>\r\n                                            <h3 class=\"f_600 f_p t_color3\">\r\n                                                Importez et exportez vos graphes                                            <\/h3>\r\n                                                                                            <p class=\"f_300\"> Exportez ou importez vos donn\u00e9es vers un fichier texte (.csv), Excel (.xlsx) et les formats RDF (.ttl et .n3)  <\/p>\r\n                                                                                    <\/div>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/section>\r\n\r\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-73f73659 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"73f73659\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-46767f5f\" data-id=\"46767f5f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-43d361b8 elementor-widget elementor-widget-heading\" data-id=\"43d361b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">La valeur ajout\u00e9e des cartes conceptuelles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7b29bf03 elementor-widget elementor-widget-text-editor\" data-id=\"7b29bf03\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Les cartes conceptuelles \u00e9tendent les cartes mentales et permettent \u00e0 deux n\u0153uds quelconques d&#8217;\u00eatre connect\u00e9s l&#8217;un \u00e0 l&#8217;autre. S\u00e9mantiquement, toutes les relations, m\u00eame les plus complexes, peuvent \u00eatre cartographi\u00e9es de cette fa\u00e7on.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2a0e47be\" data-id=\"2a0e47be\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11fec5e6 elementor-widget elementor-widget-image\" data-id=\"11fec5e6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"386\" src=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-17-38-Linkfacts-768x386.png\" class=\"attachment-medium_large size-medium_large wp-image-16292\" alt=\"Importance of concept mapping with the example of philosophical graph\" srcset=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-17-38-Linkfacts-768x386.png 768w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-17-38-Linkfacts-300x151.png 300w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-17-38-Linkfacts-1024x515.png 1024w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-17-38-Linkfacts-1536x772.png 1536w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-17-38-Linkfacts-2048x1030.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-59b15884 elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"59b15884\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-115bd929\" data-id=\"115bd929\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3066fa99 elementor-widget elementor-widget-image\" data-id=\"3066fa99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"400\" src=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/templates-800x400.png\" class=\"attachment-saasland_800x400 size-saasland_800x400 wp-image-16307\" alt=\"diff\u00e9rents types de cartographie conceptuelle\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-561eb1e8 inverse-order\" data-id=\"561eb1e8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1ce9a560 elementor-widget elementor-widget-heading\" data-id=\"1ce9a560\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Diff\u00e9rents types de cartes conceptuelles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-28d6ac80 elementor-widget elementor-widget-text-editor\" data-id=\"28d6ac80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Les cartes de cat\u00e9gorisation, les cartes de d\u00e9pendances, les taxonomies et les cartes d&#8217;analyse de risques ne sont que quelques exemples de l&#8217;\u00e9norme champ d&#8217;applications des cartes conceptuelles.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2a178ebf elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2a178ebf\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4aa6b365\" data-id=\"4aa6b365\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-439e5bc8 elementor-widget elementor-widget-heading\" data-id=\"439e5bc8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Naviguez sur l'int\u00e9gralit\u00e9 des cartes conceptuelles<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-666c188a elementor-widget elementor-widget-text-editor\" data-id=\"666c188a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span data-contrast=\"none\">Les n\u0153uds de chaque carte peuvent \u00eatre recherch\u00e9s et affich\u00e9s en un seul clic. LinkFacts permet de naviguer dans les d\u00e9tails sur n&#8217;importe quel endroit de votre carte. Passez en mode cartographie mentale pour travailler les d\u00e9tails<\/span><span data-ccp-props=\"{}\">.<\/span><\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-200b0f90\" data-id=\"200b0f90\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-18fbf45e elementor-widget elementor-widget-image\" data-id=\"18fbf45e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"386\" src=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-19-18-Linkfacts-Graphs-768x386.png\" class=\"attachment-medium_large size-medium_large wp-image-16295\" alt=\"Navigate through concept maps\" srcset=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-19-18-Linkfacts-Graphs-768x386.png 768w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-19-18-Linkfacts-Graphs-300x151.png 300w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-19-18-Linkfacts-Graphs-1024x515.png 1024w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-19-18-Linkfacts-Graphs-1536x772.png 1536w, https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/07\/Screenshot-2021-07-13-at-10-19-18-Linkfacts-Graphs-2048x1030.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e3ebc4e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e3ebc4e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-16f2968f\" data-id=\"16f2968f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3af78f53 elementor-widget elementor-widget-saasland_services_shapes\" data-id=\"3af78f53\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"saasland_services_shapes.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t       <!--============ Car Testimonial Area ==============-->\r\n        <section class=\"service_promo_area\">\r\n        <div class=\"shape_top\">\r\n            \r\n            \r\n            \r\n                     <\/div>\r\n         <div class=\"s_service_section\">\r\n             <div class=\"container custom_container\">\r\n                     <h2 class=\"f_p f_size_30 l_height50 f_600 t_color text-center\">\r\n                         Commencez avec des mod\u00e8les de cartes conceptuelles                     <\/h2>\r\n\r\n                                      <p class=\"f_300 text-center f_size_18 l_height34\"> Utilisez un mod\u00e8le pr\u00eat \u00e0 l'emploi et commencez \u00e0 utiliser LinkFacts en moins d'une minute. <\/p>\r\n                                  <div class=\"row s_service_info mt_70\">\r\n                                      <div class=\"col-lg-6 col-sm-6\">\r\n                     <div class=\"s_service_item elementor-repeater-item-14aa832\">\r\n                         <div class=\"icon icon_1\">\r\n                             <i class=\"ti-light-bulb\"><\/i>\r\n                         <\/div>\r\n                         <h3 class=\"f_p f_size_20 f_600 t_color color_box\"> Id\u00e9es et concepts <\/h3>\r\n                         <p class=\"l_height28\">  <\/p>\r\n                                                      <a href=\"#\" class=\"learn_btn_two\" >\r\n                                 Utiliser le mod\u00e8le                                 <i class=\"ti-arrow-right\"><\/i>\r\n                             <\/a>\r\n                                              <\/div>\r\n                     <\/div>\r\n                                      <div class=\"col-lg-6 col-sm-6\">\r\n                     <div class=\"s_service_item elementor-repeater-item-454ba57\">\r\n                         <div class=\"icon icon_1\">\r\n                             <i class=\"ti-link\"><\/i>\r\n                         <\/div>\r\n                         <h3 class=\"f_p f_size_20 f_600 t_color color_box\"> Cartographie des relations entre les objets <\/h3>\r\n                         <p class=\"l_height28\">  <\/p>\r\n                                                      <a href=\"#\" class=\"learn_btn_two\" >\r\n                                 Utiliser le mod\u00e8le                                 <i class=\"ti-arrow-right\"><\/i>\r\n                             <\/a>\r\n                                              <\/div>\r\n                     <\/div>\r\n                                                   <\/div>\r\n             <\/div>\r\n         <\/div>\r\n                 <\/section>\r\n       \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-34887f4 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"34887f4\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1bef9b2\" data-id=\"1bef9b2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7200fd16 elementor-widget elementor-widget-saasland_c2a\" data-id=\"7200fd16\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"saasland_c2a.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<section class=\"action_area_three sec_pad\">\r\n    <div class=\"curved\"><\/div>\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-lg-12\">\r\n                <div class=\"action_content text-center\">\r\n                                        <h2 class=\"f_600 f_size_30 l_height45 mb_40\">\r\n                    Pr\u00eat \u00e0 commencer avec LinkFacts ?<br \/>\r\nC'est facile et gratuit \u00e0 vie !                <\/h2>\r\n                                                    <a href=\"https:\/\/one.linkfacts.link\/user\/signUp\"\r\n                                                                       class=\"about_btn white_btn wow fadeInLeft\" data-wow-delay=\"0.3s\">\r\n                        Commencer en une minute                    <\/a>\r\n                                                    <a href=\"https:\/\/calendly.com\/linkfacts\/demo-linkfacts\"\r\n                                                                       class=\"about_btn wow fadeInRight\" data-wow-delay=\"0.4s\">\r\n                        R\u00e9server une d\u00e9mo gratuite                    <\/a>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <\/div>\r\n<\/section>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Outil gratuit de cartes conceptuelles en ligne Visualisez et clarifiez des concepts simples ou complexes avec LinkFacts.\u202fReliez des documents, des ic\u00f4nes, des notes ou des formes pour visualiser les liens entre les id\u00e9es et les sujets dans votre carte conceptuelle. Visualisez vos informations Partagez, commentez, \u00e9valuez Joignez des sources et des documents Commencer gratuitement Des&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"footnotes":""},"class_list":["post-16315","page","type-page","status-publish","hentry","no-post-thumbnail"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Outil gratuit de cartes conceptuelles en ligne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Outil gratuit de cartes conceptuelles en ligne\" \/>\n<meta property=\"og:description\" content=\"Outil gratuit de cartes conceptuelles en ligne Visualisez et clarifiez des concepts simples ou complexes avec LinkFacts.\u202fReliez des documents, des ic\u00f4nes, des notes ou des formes pour visualiser les liens entre les id\u00e9es et les sujets dans votre carte conceptuelle. Visualisez vos informations Partagez, commentez, \u00e9valuez Joignez des sources et des documents Commencer gratuitement Des...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/\" \/>\n<meta property=\"og:site_name\" content=\"LinkFacts | Collaborative platform to visually explore, capture and share knowledge\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LinkFacts\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-03T14:31:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@linkfacts1\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/\",\"url\":\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/\",\"name\":\"Outil gratuit de cartes conceptuelles en ligne\",\"isPartOf\":{\"@id\":\"https:\/\/www.linkfacts.link\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png\",\"datePublished\":\"2021-07-13T08:38:02+00:00\",\"dateModified\":\"2022-02-03T14:31:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#primaryimage\",\"url\":\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png\",\"contentUrl\":\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.linkfacts.link\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cartes conceptuelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.linkfacts.link\/fr\/#website\",\"url\":\"https:\/\/www.linkfacts.link\/fr\/\",\"name\":\"LinkFacts | Collaborative platform to visually explore, capture and share knowledge\",\"description\":\"Une plateforme interactive unique pour cr\u00e9er, modifier et partager des cartes mentales.\",\"publisher\":{\"@id\":\"https:\/\/www.linkfacts.link\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.linkfacts.link\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.linkfacts.link\/fr\/#organization\",\"name\":\"LinkFacts\",\"url\":\"https:\/\/www.linkfacts.link\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.linkfacts.link\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2018\/11\/linkfacts-logo-512.png\",\"contentUrl\":\"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2018\/11\/linkfacts-logo-512.png\",\"width\":512,\"height\":512,\"caption\":\"LinkFacts\"},\"image\":{\"@id\":\"https:\/\/www.linkfacts.link\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/LinkFacts\",\"https:\/\/x.com\/linkfacts1\",\"https:\/\/lu.linkedin.com\/company\/linkfacts\",\"https:\/\/www.youtube.com\/channel\/UCb7ySsUoUYJ0uvi9X1566IA\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Outil gratuit de cartes conceptuelles en ligne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/","og_locale":"fr_FR","og_type":"article","og_title":"Outil gratuit de cartes conceptuelles en ligne","og_description":"Outil gratuit de cartes conceptuelles en ligne Visualisez et clarifiez des concepts simples ou complexes avec LinkFacts.\u202fReliez des documents, des ic\u00f4nes, des notes ou des formes pour visualiser les liens entre les id\u00e9es et les sujets dans votre carte conceptuelle. Visualisez vos informations Partagez, commentez, \u00e9valuez Joignez des sources et des documents Commencer gratuitement Des...","og_url":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/","og_site_name":"LinkFacts | Collaborative platform to visually explore, capture and share knowledge","article_publisher":"https:\/\/www.facebook.com\/LinkFacts","article_modified_time":"2022-02-03T14:31:39+00:00","og_image":[{"url":"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@linkfacts1","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/","url":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/","name":"Outil gratuit de cartes conceptuelles en ligne","isPartOf":{"@id":"https:\/\/www.linkfacts.link\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#primaryimage"},"image":{"@id":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png","datePublished":"2021-07-13T08:38:02+00:00","dateModified":"2022-02-03T14:31:39+00:00","breadcrumb":{"@id":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#primaryimage","url":"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png","contentUrl":"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2021\/06\/MicrosoftTeams-image-2.png"},{"@type":"BreadcrumbList","@id":"https:\/\/www.linkfacts.link\/fr\/cartes-conceptuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.linkfacts.link\/fr\/"},{"@type":"ListItem","position":2,"name":"Cartes conceptuelles"}]},{"@type":"WebSite","@id":"https:\/\/www.linkfacts.link\/fr\/#website","url":"https:\/\/www.linkfacts.link\/fr\/","name":"LinkFacts | Collaborative platform to visually explore, capture and share knowledge","description":"Une plateforme interactive unique pour cr\u00e9er, modifier et partager des cartes mentales.","publisher":{"@id":"https:\/\/www.linkfacts.link\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.linkfacts.link\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.linkfacts.link\/fr\/#organization","name":"LinkFacts","url":"https:\/\/www.linkfacts.link\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.linkfacts.link\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2018\/11\/linkfacts-logo-512.png","contentUrl":"https:\/\/www.linkfacts.link\/wp-content\/uploads\/2018\/11\/linkfacts-logo-512.png","width":512,"height":512,"caption":"LinkFacts"},"image":{"@id":"https:\/\/www.linkfacts.link\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LinkFacts","https:\/\/x.com\/linkfacts1","https:\/\/lu.linkedin.com\/company\/linkfacts","https:\/\/www.youtube.com\/channel\/UCb7ySsUoUYJ0uvi9X1566IA"]}]}},"_links":{"self":[{"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/pages\/16315","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/comments?post=16315"}],"version-history":[{"count":1,"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/pages\/16315\/revisions"}],"predecessor-version":[{"id":24671,"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/pages\/16315\/revisions\/24671"}],"wp:attachment":[{"href":"https:\/\/www.linkfacts.link\/fr\/wp-json\/wp\/v2\/media?parent=16315"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}